{"id":195,"date":"2025-01-20T11:10:38","date_gmt":"2025-01-20T11:10:38","guid":{"rendered":"https:\/\/nounou-marrakech.com\/?page_id=195"},"modified":"2025-01-30T11:14:56","modified_gmt":"2025-01-30T11:14:56","slug":"daytime-babysitter","status":"publish","type":"page","link":"https:\/\/nounou-marrakech.com\/en\/services\/baby-sitter-de-jour\/","title":{"rendered":"Day babysitter"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"195\" class=\"elementor elementor-195\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2081e387 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2081e387\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bc626a0\" data-id=\"6bc626a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53ecb4c4 de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"53ecb4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Baby-sitter de jour<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ead0e55 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"4ead0e55\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/askproject.net\/tinyhugs\/home\/\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">NouNou Pro Marrakech<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Baby-sitter de jour<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cec924d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cec924d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1248289a\" data-id=\"1248289a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-670bc22a de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"670bc22a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Garde d'enfants en journ\u00e9e \u00e0 Marrakech<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb6c44 de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"3bb6c44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez <strong>Nounou Pro Marrakech<\/strong>, nous comprenons \u00e0 quel point il est essentiel de trouver une aide fiable et professionnelle pour prendre soin de vos enfants pendant la journ\u00e9e. Avec notre service <strong>Aide de jour<\/strong>, nous vous offrons une solution sur mesure qui garantit le bien-\u00eatre et la s\u00e9curit\u00e9 de vos petits tout en vous apportant une tranquillit\u00e9 d&rsquo;esprit in\u00e9gal\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-31f186ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31f186ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48c3577d\" data-id=\"48c3577d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2616d045 de_scroll_animation_no elementor-widget elementor-widget-image\" data-id=\"2616d045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/housewife-mom-spends-time-with-small-children-at-h-EHE4UFS-1024x683.jpg\" class=\"attachment-large size-large wp-image-143\" alt=\"\" srcset=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/housewife-mom-spends-time-with-small-children-at-h-EHE4UFS-1024x683.jpg 1024w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/housewife-mom-spends-time-with-small-children-at-h-EHE4UFS-300x200.jpg 300w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/housewife-mom-spends-time-with-small-children-at-h-EHE4UFS-768x512.jpg 768w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/housewife-mom-spends-time-with-small-children-at-h-EHE4UFS-1536x1024.jpg 1536w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/housewife-mom-spends-time-with-small-children-at-h-EHE4UFS-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ce87a84\" data-id=\"3ce87a84\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-525877ec de_scroll_animation_no elementor-widget elementor-widget-elementskit-video\" data-id=\"525877ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"video-content\" data-video-player=\"[]\" data-video-setting=\"{&quot;videoVolume&quot;:&quot;horizontal&quot;,&quot;startVolume&quot;:0.8,&quot;videoType&quot;:&quot;iframe&quot;,&quot;videoClass&quot;:&quot;mfp-fade&quot;,&quot;videoStyle&quot;:&quot;popup&quot;,&quot;videoTypeName&quot;:&quot;youtube&quot;,&quot;autoplay&quot;:false,&quot;muted&quot;:false,&quot;loop&quot;:false}\">\n\t\t\t\n<a class=\"ekit_icon_button glow-ripple ekit-video-popup ekit-video-popup-btn\" href=\"https:\/\/www.youtube.com\/embed\/VhBl3dHT5SY?feature=oembed?playlist=VhBl3dHT5SY&amp;mute=0&amp;autoplay=0&amp;loop=no&amp;controls=0&amp;start=0&amp;end=\" aria-label=\"video-popup\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-play1\"><\/i>\t\t\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"ekit-hidden-icons\" hidden aria-hidden=\"true\">\n\t\t\t\t\t<i class=\"ekit-popup-close-icon icon icon-cancel\"><\/i>\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ab7daa de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"45ab7daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir notre service Aide de jour ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46d55ed7 de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"46d55ed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Professionnalisme et Exp\u00e9rience :<\/strong> Nos nounous sont soigneusement s\u00e9lectionn\u00e9es pour leur expertise en garde d\u2019enfants et leur bienveillance. Elles b\u00e9n\u00e9ficient de formations sp\u00e9cialis\u00e9es pour r\u00e9pondre aux besoins des enfants de tout \u00e2ge.<\/p><\/li><li><p><strong>Flexibilit\u00e9 Adapt\u00e9e \u00e0 Vos Besoins :<\/strong> Que ce soit pour une garde \u00e0 temps plein, \u00e0 temps partiel ou pour des horaires sp\u00e9cifiques, nous nous adaptons \u00e0 votre emploi du temps.<\/p><\/li><li><p><strong>Encadrement et Activit\u00e9s Ludiques :<\/strong> Nos aides de jour proposent des activit\u00e9s \u00e9ducatives et divertissantes adapt\u00e9es \u00e0 l\u2019\u00e2ge et aux int\u00e9r\u00eats de vos enfants, stimulant ainsi leur d\u00e9veloppement.<\/p><\/li><li><p><strong>S\u00e9curit\u00e9 et Confiance :<\/strong> La s\u00e9curit\u00e9 de vos enfants est notre priorit\u00e9 absolue. Chaque aide de jour est rigoureusement v\u00e9rifi\u00e9e et dispose de r\u00e9f\u00e9rences fiables.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14f3a12 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"14f3a12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ce que comprend notre service Aide de jour :\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a805fe5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a805fe5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-70a06b28\" data-id=\"70a06b28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5421f7dc elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width de_scroll_animation_no elementor-widget elementor-widget-icon-list\" data-id=\"5421f7dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-tick\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garde d'enfants \u00e0 domicile : Une attention personnalis\u00e9e dans un environnement familier pour vos enfants.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-tick\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accompagnement quotidien : Aide aux repas, \u00e0 l\u2019hygi\u00e8ne, et \u00e0 l\u2019organisation des routines.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-tick\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Activit\u00e9s \u00e9ducatives et r\u00e9cr\u00e9atives : Jeux, apprentissage ludique, et d\u00e9couvertes pour d\u00e9velopper les comp\u00e9tences et la cr\u00e9ativit\u00e9 des enfants.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-tick\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soutien aux parents : Assistance pour all\u00e9ger votre charge quotidienne tout en respectant vos consignes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ccf7a5 de_scroll_animation_no elementor-widget elementor-widget-image-carousel\" data-id=\"9ccf7a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/happy-baby-sitting-on-the-kitchen-table-with-mom-s-K5D9ELD-1024x683.jpg\" alt=\"service de baby-sitting \u00e0 Marrakech pour familles et touristes\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/mom-holds-and-kisses-the-baby-caring-for-the-baby-LCCU6KC-1024x683.jpg\" alt=\"mom-holds-and-kisses-the-baby-caring-for-the-baby-LCCU6KC.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/father-comforting-crying-baby-FKYUXBB-1024x683.jpg\" alt=\"father-comforting-crying-baby-FKYUXBB.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/children-making-handmade-cards-D2RBXPU-1024x683.jpg\" alt=\"children-making-handmade-cards-D2RBXPU.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/gentle-maternal-care-mom-kisses-the-baby-sitting-22BM5NZ-1024x683.jpg\" alt=\"gentle-maternal-care-mom-kisses-the-baby-sitting-22BM5NZ.jpg\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54e293da de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"54e293da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos engagements envers les familles :<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4613853a de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"4613853a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Une transparence totale dans la s\u00e9lection de nos aides de jour.<\/li><li>Une communication continue pour r\u00e9pondre \u00e0 vos questions et assurer un suivi r\u00e9gulier.<\/li><li>Une prestation de haute qualit\u00e9 adapt\u00e9e \u00e0 vos attentes et aux besoins sp\u00e9cifiques de vos enfants.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d81db93 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"d81db93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment r\u00e9server notre service Aide de jour ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39a7f52 de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"39a7f52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><strong>Contactez-nous :<\/strong> Appelez-nous ou remplissez le formulaire sur notre site pour d\u00e9crire vos besoins.<\/li><li><strong>Consultation gratuite :<\/strong> Nous organisons un entretien pour comprendre vos attentes et choisir l\u2019aide de jour id\u00e9ale.<\/li><li><strong>Mise en place rapide :<\/strong> Apr\u00e8s validation, notre nounou d\u00e9marre imm\u00e9diatement pour accompagner vos enfants dans leur quotidien.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5dae7a8\" data-id=\"5dae7a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fcb0ab9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcb0ab9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cd0a17f\" data-id=\"cd0a17f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7666e48 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"7666e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entrer en contact<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ade978 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"7ade978\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAddress\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRue 73 IBN AICHA Gueliz <br> Marrakech, Maroc \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b391cd7 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"b391cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPhone\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t+212 601293041 <br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f5a9b2 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"5f5a9b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEmail\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tmarrakechnounou@mail.com <br> \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb31df2 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"cb31df2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">R\u00e9server  Maintenant<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-480d648 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"480d648\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c866e9c elementor-invisible\" data-id=\"c866e9c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d30fc1 elementor-button-align-stretch de_scroll_animation_no elementor-widget elementor-widget-form\" data-id=\"8d30fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"195\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"8d30fc1\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Baby-sitter de Jour : Garde d&#039;Enfants de Qualit\u00e9 pour la Journ\u00e9e\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"195\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom et pr\u00e9nom \t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom et pr\u00e9nom \">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVotre adresse email\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"adresse@gmail.com\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_cf0607f elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_cf0607f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVotre t\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_cf0607f]\" id=\"form-field-field_cf0607f\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"+212 515116166\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_4e11220 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_4e11220\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVous \u00eates\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Un Parent \" id=\"form-field-field_4e11220-0\" name=\"form_fields[field_4e11220][]\"> <label for=\"form-field-field_4e11220-0\">Un Parent <\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"une Nounou\" id=\"form-field-field_4e11220-1\" name=\"form_fields[field_4e11220][]\"> <label for=\"form-field-field_4e11220-1\">une Nounou<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Une Entreprise \" id=\"form-field-field_4e11220-2\" name=\"form_fields[field_4e11220][]\"> <label for=\"form-field-field_4e11220-2\">Une Entreprise <\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVotre demande\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-995c47a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"995c47a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48c05269\" data-id=\"48c05269\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ba71ddb de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3ba71ddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Autres services<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ba1cd94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ba1cd94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1a08f173 elementor-invisible\" data-id=\"1a08f173\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70d02aad elementor-position-top de_scroll_animation_no elementor-widget elementor-widget-image-box\" data-id=\"70d02aad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1201\" height=\"1201\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-2.png\" class=\"elementor-animation-float attachment-full size-full wp-image-31\" alt=\"\" srcset=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-2.png 1201w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-2-300x300.png 300w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-2-1024x1024.png 1024w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-2-150x150.png 150w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-2-768x768.png 768w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Baby-sitters en soir\u00e9e<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6047ef elementor-align-center de_scroll_animation_no elementor-widget elementor-widget-button\" data-id=\"3e6047ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-731cd1fa elementor-invisible\" data-id=\"731cd1fa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:800}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3732551f elementor-position-top de_scroll_animation_no elementor-widget elementor-widget-image-box\" data-id=\"3732551f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1201\" height=\"1201\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-4.png\" class=\"elementor-animation-float attachment-full size-full wp-image-32\" alt=\"\" srcset=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-4.png 1201w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-4-300x300.png 300w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-4-1024x1024.png 1024w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-4-150x150.png 150w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-4-768x768.png 768w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Baby-sitters d'h\u00f4tel<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dce4ea2 elementor-align-center de_scroll_animation_no elementor-widget elementor-widget-button\" data-id=\"1dce4ea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6206960 elementor-invisible\" data-id=\"6206960\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:1000}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cb30176 elementor-position-top de_scroll_animation_no elementor-widget elementor-widget-image-box\" data-id=\"4cb30176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1201\" height=\"1201\" src=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-3.png\" class=\"elementor-animation-float attachment-full size-full wp-image-33\" alt=\"\" srcset=\"https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-3.png 1201w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-3-300x300.png 300w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-3-1024x1024.png 1024w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-3-150x150.png 150w, https:\/\/nounou-marrakech.com\/wp-content\/uploads\/2025\/01\/icon-3-768x768.png 768w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Garde d'enfants \u00e9v\u00e9nementielle<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4942486a elementor-align-center de_scroll_animation_no elementor-widget elementor-widget-button\" data-id=\"4942486a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Baby-sitter de jour NouNou Pro Marrakech Baby-sitter de jour Garde d&rsquo;enfants en journ\u00e9e \u00e0 Marrakech Chez Nounou Pro Marrakech, nous comprenons \u00e0 quel point il est essentiel de trouver une aide fiable et professionnelle pour prendre soin de vos enfants pendant la journ\u00e9e. Avec notre service Aide de jour, nous vous offrons une solution sur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":251,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-195","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/pages\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":13,"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/pages\/195\/revisions"}],"predecessor-version":[{"id":241,"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/pages\/195\/revisions\/241"}],"up":[{"embeddable":true,"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/pages\/251"}],"wp:attachment":[{"href":"https:\/\/nounou-marrakech.com\/en\/wp-json\/wp\/v2\/media?parent=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}